{"id":4270,"date":"2025-03-30T04:47:33","date_gmt":"2025-03-30T04:47:33","guid":{"rendered":"https:\/\/pointarenaschools.org\/pahs\/?p=4270"},"modified":"2025-03-30T04:47:34","modified_gmt":"2025-03-30T04:47:34","slug":"diy-arcade-machine-project","status":"publish","type":"post","link":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/","title":{"rendered":"DIY Arcade Machine Project"},"content":{"rendered":"<p><span style=\"caret-color: #004b8e; color: #004b8e; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-size: 18px; font-style: normal; font-variant-caps: normal; font-weight: bold; letter-spacing: normal; orphans: auto; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: auto; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration: none; display: inline !important; float: none;\">Gaming Club is offering a DIY Arcade Machine Project<\/span><\/p>\n<p><a href=\"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/screenshot-2025-03-29-at-9-34-18-pm\/\" rel=\"attachment wp-att-4271\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4271\" src=\"http:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.18\u202fPM.png\" alt=\"\" width=\"960\" height=\"1238\" srcset=\"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.18\u202fPM.png 960w, https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.18\u202fPM-233x300.png 233w, https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.18\u202fPM-794x1024.png 794w, https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.18\u202fPM-768x990.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a> <a href=\"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/screenshot-2025-03-29-at-9-34-27-pm\/\" rel=\"attachment wp-att-4272\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4272\" src=\"http:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.27\u202fPM.png\" alt=\"\" width=\"950\" height=\"1228\" srcset=\"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.27\u202fPM.png 950w, https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.27\u202fPM-232x300.png 232w, https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.27\u202fPM-792x1024.png 792w, https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2025\/03\/Screenshot-2025-03-29-at-9.34.27\u202fPM-768x993.png 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gaming Club is offering a DIY Arcade Machine Project<\/p>\n","protected":false},"author":1,"featured_media":3001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIY Arcade Machine Project - Point Arena High School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIY Arcade Machine Project - Point Arena High School\" \/>\n<meta property=\"og:description\" content=\"Gaming Club is offering a DIY Arcade Machine Project\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/\" \/>\n<meta property=\"og:site_name\" content=\"Point Arena High School\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-30T04:47:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-30T04:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2023\/06\/action-network.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"blake88\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"blake88\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/\"},\"author\":{\"name\":\"blake88\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#\\\/schema\\\/person\\\/553aaf00ffcc82433deee14e34d01f01\"},\"headline\":\"DIY Arcade Machine Project\",\"datePublished\":\"2025-03-30T04:47:33+00:00\",\"dateModified\":\"2025-03-30T04:47:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/\"},\"wordCount\":13,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/action-network.webp\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/\",\"url\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/\",\"name\":\"DIY Arcade Machine Project - Point Arena High School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/action-network.webp\",\"datePublished\":\"2025-03-30T04:47:33+00:00\",\"dateModified\":\"2025-03-30T04:47:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/action-network.webp\",\"contentUrl\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/action-network.webp\",\"width\":1140,\"height\":844,\"caption\":\"action network\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/diy-arcade-machine-project\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIY Arcade Machine Project\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#website\",\"url\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/\",\"name\":\"Point Arena High School\",\"description\":\"Fostering Lifelong Learning\",\"publisher\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#organization\",\"name\":\"Point Arena High School\",\"url\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/PAHS-web-header7.jpg\",\"contentUrl\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/PAHS-web-header7.jpg\",\"width\":720,\"height\":108,\"caption\":\"Point Arena High School\"},\"image\":{\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/#\\\/schema\\\/person\\\/553aaf00ffcc82433deee14e34d01f01\",\"name\":\"blake88\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c04d03a44e3f0f6d2bfca1d5fc193dc42c79b8aed5d3cbac6d2a0b5b4fda208b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c04d03a44e3f0f6d2bfca1d5fc193dc42c79b8aed5d3cbac6d2a0b5b4fda208b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c04d03a44e3f0f6d2bfca1d5fc193dc42c79b8aed5d3cbac6d2a0b5b4fda208b?s=96&d=mm&r=g\",\"caption\":\"blake88\"},\"url\":\"https:\\\/\\\/pointarenaschools.org\\\/pahs\\\/author\\\/blake88\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIY Arcade Machine Project - Point Arena High School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/","og_locale":"en_US","og_type":"article","og_title":"DIY Arcade Machine Project - Point Arena High School","og_description":"Gaming Club is offering a DIY Arcade Machine Project","og_url":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/","og_site_name":"Point Arena High School","article_published_time":"2025-03-30T04:47:33+00:00","article_modified_time":"2025-03-30T04:47:34+00:00","og_image":[{"width":1140,"height":844,"url":"http:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2023\/06\/action-network.webp","type":"image\/webp"}],"author":"blake88","twitter_card":"summary_large_image","twitter_misc":{"Written by":"blake88","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#article","isPartOf":{"@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/"},"author":{"name":"blake88","@id":"https:\/\/pointarenaschools.org\/pahs\/#\/schema\/person\/553aaf00ffcc82433deee14e34d01f01"},"headline":"DIY Arcade Machine Project","datePublished":"2025-03-30T04:47:33+00:00","dateModified":"2025-03-30T04:47:34+00:00","mainEntityOfPage":{"@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/"},"wordCount":13,"commentCount":0,"publisher":{"@id":"https:\/\/pointarenaschools.org\/pahs\/#organization"},"image":{"@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#primaryimage"},"thumbnailUrl":"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2023\/06\/action-network.webp","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/","url":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/","name":"DIY Arcade Machine Project - Point Arena High School","isPartOf":{"@id":"https:\/\/pointarenaschools.org\/pahs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#primaryimage"},"image":{"@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#primaryimage"},"thumbnailUrl":"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2023\/06\/action-network.webp","datePublished":"2025-03-30T04:47:33+00:00","dateModified":"2025-03-30T04:47:34+00:00","breadcrumb":{"@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#primaryimage","url":"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2023\/06\/action-network.webp","contentUrl":"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2023\/06\/action-network.webp","width":1140,"height":844,"caption":"action network"},{"@type":"BreadcrumbList","@id":"https:\/\/pointarenaschools.org\/pahs\/diy-arcade-machine-project\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pointarenaschools.org\/pahs\/"},{"@type":"ListItem","position":2,"name":"DIY Arcade Machine Project"}]},{"@type":"WebSite","@id":"https:\/\/pointarenaschools.org\/pahs\/#website","url":"https:\/\/pointarenaschools.org\/pahs\/","name":"Point Arena High School","description":"Fostering Lifelong Learning","publisher":{"@id":"https:\/\/pointarenaschools.org\/pahs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pointarenaschools.org\/pahs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pointarenaschools.org\/pahs\/#organization","name":"Point Arena High School","url":"https:\/\/pointarenaschools.org\/pahs\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pointarenaschools.org\/pahs\/#\/schema\/logo\/image\/","url":"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2022\/11\/PAHS-web-header7.jpg","contentUrl":"https:\/\/pointarenaschools.org\/pahs\/wp-content\/uploads\/2022\/11\/PAHS-web-header7.jpg","width":720,"height":108,"caption":"Point Arena High School"},"image":{"@id":"https:\/\/pointarenaschools.org\/pahs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pointarenaschools.org\/pahs\/#\/schema\/person\/553aaf00ffcc82433deee14e34d01f01","name":"blake88","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c04d03a44e3f0f6d2bfca1d5fc193dc42c79b8aed5d3cbac6d2a0b5b4fda208b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c04d03a44e3f0f6d2bfca1d5fc193dc42c79b8aed5d3cbac6d2a0b5b4fda208b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c04d03a44e3f0f6d2bfca1d5fc193dc42c79b8aed5d3cbac6d2a0b5b4fda208b?s=96&d=mm&r=g","caption":"blake88"},"url":"https:\/\/pointarenaschools.org\/pahs\/author\/blake88\/"}]}},"_links":{"self":[{"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/posts\/4270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/comments?post=4270"}],"version-history":[{"count":2,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/posts\/4270\/revisions"}],"predecessor-version":[{"id":4274,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/posts\/4270\/revisions\/4274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/media\/3001"}],"wp:attachment":[{"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/media?parent=4270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/categories?post=4270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pointarenaschools.org\/pahs\/wp-json\/wp\/v2\/tags?post=4270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}